{"id":6526,"date":"2023-02-02T03:21:05","date_gmt":"2023-02-02T02:21:05","guid":{"rendered":"https:\/\/julienmarchal.fr\/?page_id=6526"},"modified":"2023-03-09T23:20:18","modified_gmt":"2023-03-09T22:20:18","slug":"logbook","status":"publish","type":"page","link":"https:\/\/julienmarchal.fr\/en-us\/journal-de-bord\/","title":{"rendered":"Logbook"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6526\" class=\"elementor elementor-6526\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1099949 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1099949\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de4cf02\" data-id=\"de4cf02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec002e elementor-widget elementor-widget-wgl-menu\" data-id=\"eec002e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class='primary-nav'><ul id=\"menu-filtres-journal-de-bord\" class=\"menu\"><li id=\"menu-item-8176\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8176\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/journal-de-bord\/\"><span><span class=\"item_text\">Tout le journal<\/span><i class=\"menu-item__plus\"><\/i><\/span><\/a><\/li><li id=\"menu-item-8144\" class=\"menu-item menu-item-type-taxonomy menu-item-object-category menu-item-8144\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\"><span><span class=\"item_text\">Travaux personnels<\/span><i class=\"menu-item__plus\"><\/i><\/span><\/a><\/li><li id=\"menu-item-8145\" class=\"menu-item menu-item-type-taxonomy menu-item-object-category menu-item-8145\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\"><span><span class=\"item_text\">Photos Clients<\/span><i class=\"menu-item__plus\"><\/i><\/span><\/a><\/li><li id=\"menu-item-8143\" class=\"menu-item menu-item-type-taxonomy menu-item-object-category menu-item-8143\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\"><span><span class=\"item_text\">Blog g\u00e9n\u00e9ral<\/span><i class=\"menu-item__plus\"><\/i><\/span><\/a><\/li><\/ul><\/nav><div class=\"mobile-hamburger-toggle\"><div class=\"hamburger-box\"><div class=\"hamburger-inner\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3ab60 elementor-widget elementor-widget-wgl-blog\" data-id=\"2d3ab60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;blog_columns&quot;:&quot;6&quot;}\" data-widget_type=\"wgl-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"wgl_cpt_section\"><div class=\"blog-posts\"><div class=\"container-grid row  blog_columns-2 grid blog-style-standard\"><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/quatrieme-hiver-comme-timonier-entre-les-iles-de-la-madeleine-et-montreal\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2024\/11\/ctma-2-2024-jm-1170x725.webp' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/quatrieme-hiver-comme-timonier-entre-les-iles-de-la-madeleine-et-montreal\/\">Quatri\u00e8me hiver comme timonier entre les \u00celes de la Madeleine et Montr\u00e9al au Canada.<\/a><\/h3><div class=\"blog-post_text\"><p>Je continue cet hiver mon travail en tant que timonier ou matelot de quart passerelle sur un bateau de la firme CTMA (Coop\u00e9rative de Transport...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/observateur-et-operateur-de-systeme-acoustique-sur-les-mammiferes-marins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2024\/10\/dragage-mmo-ram-4-2024-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/observateur-et-operateur-de-systeme-acoustique-sur-les-mammiferes-marins\/\">Observateur et op\u00e9rateur de syst\u00e8me d\u2019acoustique sur les mammif\u00e8res marins<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai effectu\u00e9 un contrat comme observateur et op\u00e9rateur de syst\u00e8me d\u2019acoustique pour les de mammif\u00e8res marins lors d\u2019un dragage pour un...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2024-au-canada\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2024\/10\/saison-2024-croisieres-essipit-julien-marchal-15-1-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2024-au-canada\/\">Saison 2024 au Canada<\/a><\/h3><div class=\"blog-post_text\"><p>Concernant les belles observations en mer, j\u2019en retiens plusieurs. Tout d\u2019abord les deux baleines \u00e0 bosses, Gaspar et Irisept\/Cocotte, en...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/acoustique-mammiferes-marins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/10\/mmo-julien-marchal-6-2023-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/acoustique-mammiferes-marins\/\">Acoustique sur les mammif\u00e8res marins<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai effectu\u00e9 pendant le mois d&#8217;octobre 2023, un contrat comme Observateur de Mammif\u00e8res Marins (OMM) et Op\u00e9rateur de syst\u00e8me...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2023-canada\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/10\/client-essipit-27-julien-marchal-saison-2023-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2023-canada\/\">Saison 2023 au Canada<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai effectu\u00e9 quatre mois sur l&#8217;eau pendant la saison 2023 en totalisant 279 croisi\u00e8res. Nous avons eu un mois de juin difficile sans...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/son-acoustique-de-baleine-a-bosse\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Megaptera.Samana.Gallerie0983.mai2011-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/son-acoustique-de-baleine-a-bosse\/\">Son acoustique de baleine \u00e0 bosse<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous,\nLes baleines \u00e0 bosses sont les vraies stars de la recherche scientifique, probablement les c\u00e9tac\u00e9s les plus \u00e9tudi\u00e9s pour leurs...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/page-livre-franck-latsuna-captivite-2023\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/03\/couverture-livre-fanck-latsuna-2023-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/page-livre-franck-latsuna-captivite-2023\/\">Un po\u00e8me contre la captivit\u00e9 des orques du livre de Latsuna et Miya<\/a><\/h3><div class=\"blog-post_text\"><p>L&#8217;une des pages du livre de mon ami Franck Latsuna &#8220;\u00c0 la lisi\u00e8re de l&#8217;homme, po\u00e8mes illustr\u00e9s&#8221;, contre la captivit\u00e9.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/creation-et-dessins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/creation-et-dessins\/\">Cr\u00e9ation et dessins<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour tout le monde\nLorsque je contactais mon coiffeur qui s\u2019occupait de moi en France, il me parlait souvent de mes cartes postales de voyages...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/timonier-arctique\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/arctique-2022-4-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/timonier-arctique\/\">Timonier en Arctique<\/a><\/h3><div class=\"blog-post_text\"><p>C&#8217;est cinq semaines dans l&#8217;Arctique Canadien sur un bateau cargo entre octobre et novembre 2022. Ce f\u00fbt magnifique: Iceberg, la...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2022-au-canada-2\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/croisieres-essipit-3-2022-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2022-au-canada-2\/\">Saison 2022 au Canada<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai effectu\u00e9 un bon mois sur l&#8217;eau pendant la saison 2023 en totalisant 104 croisi\u00e8res. Nous avons rencontr\u00e9 des journ\u00e9es de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/guide-des-mammiferes-marins-de-lile-maurice-de-delphine-legay-1999\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/Reef1-Mauritius-1999-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/guide-des-mammiferes-marins-de-lile-maurice-de-delphine-legay-1999\/\">Guide sur les baleines et les dauphins de l&#8217;\u00eele Maurice (1999)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai connu Delphine Legay en 1999 pour avoir travaill\u00e9 avec elle sur l&#8217;\u00cele Maurice et Iles Rodrigues. Ce guide est un bel hommage.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/mammiferes-marins-ile-maurice-et-rodriques-avec-delphine-legay-en-1999\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/cachalot-famille-legay-mauritius.19.2020-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/mammiferes-marins-ile-maurice-et-rodriques-avec-delphine-legay-en-1999\/\">Mammif\u00e8res marins: \u00cele Maurice par Delphine Legay (1999 \u00e0 2001)<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour les internautes,\nAvec la mar\u00e9e noire r\u00e9cente sur l&#8217;ile Maurice, j&#8217;\u00e9tais f\u00e2ch\u00e9 et triste de cette pollution car je connais tr\u00e8s...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/les-photos-de-la-baleine-noire-au-canada-aout-2016\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Photos-clients-saison-Essipit-2016-3-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/les-photos-de-la-baleine-noire-au-canada-aout-2016\/\">Saison 2016 : les photos de la baleine noire et la baleine \u00e0 bosse (Canada)<\/a><\/h3><div class=\"blog-post_text\"><p>Concernant la saison 2016, une seule chose: des baleines rares!\nAu d\u00e9part je devais faire que des remplacements sur l\u2019eau en tant que capitaine....<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/mission-baleine-noire-aout-2020\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/baleine-franche-right-whale-2-photo-MARS-MICS-2020-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/mission-baleine-noire-aout-2020\/\">Mission baleine noire (ao\u00fbt 2020)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai particip\u00e9 en tant que matelot \u00e0 la mission Baleine noire (Eubalaena glacialis) dans le Golfe Saint-Laurent avec l&#8217;\u00e9quipe de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-baleines-2015\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Saison2016.Essipit.Canada.jpg-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-baleines-2015\/\">Saison baleines 2015, difficile sur l&#8217;eau<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour tout le monde,\nJ\u2019ai fait aucun article concernant la saison 2015. La raison est simple : peu de baleine et saison difficile. Depuis 4 ans...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2014-au-canada-octobre-2014\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotoclientsaisonEssipit20145-scaled-1170x725.jpg' alt='SONY DSC' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2014-au-canada-octobre-2014\/\">Saison 2014 au Canada (octobre 2014)<\/a><\/h3><div class=\"blog-post_text\"><p>Concernant la saison 2014 : beaucoup moins de baleines cette ann\u00e9e !\nDepuis 2011, il y a moins de baleines, ann\u00e9e apr\u00e8s ann\u00e9e ! Dommage. En tout...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2013-au-canada-octobre-2013\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201322-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2013-au-canada-octobre-2013\/\">Saison 2013 au Canada (octobre 2013)<\/a><\/h3><div class=\"blog-post_text\"><p>Le 06 octobre 2013, j&#8217;ai termin\u00e9 ma saison sur l&#8217;eau et d\u00e9passer le nombre de mes sorties par rapport \u00e0 2012. Mon total est de 185...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-capitaine-crochet-juin-2013\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2013\/06\/capitaine-crochet-piege-a-crabe-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-capitaine-crochet-juin-2013\/\">Baleine Capitaine Crochet (juin 2013)<\/a><\/h3><div class=\"blog-post_text\"><p>Ce rorqual commun est une femelle tr\u00e8s c\u00e9l\u00e8bre dans l&#8217; est du Canada et au Qu\u00e9bec. Son nom est &#8220;Capitaine Crochet&#8221;.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/elle-arrivent-pour-la-saison-2013\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2013\/05\/whales-coming-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/elle-arrivent-pour-la-saison-2013\/\">Elle arrivent pour la saison 2013 !<\/a><\/h3><div class=\"blog-post_text\"><p>La saison estivale va bient\u00f4t commencer et nous observons les premi\u00e8res baleines en face de chez nous !<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/vacances-en-guyane-francaise\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2013\/01\/guyane-francaise-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/vacances-en-guyane-francaise\/\">Vacances en Guyane Fran\u00e7aise !<\/a><\/h3><div class=\"blog-post_text\"><p>Chers visiteurs,\nJe suis de retour au Canada apr\u00e8s un voyage d&#8217; un mois en Guyane Fran\u00e7aise pour rencontrer la belle-famille.\nNous avons...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/vacances-en-guyane-francaise-janvier-2013\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/Guyanefrancaise20133-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/vacances-en-guyane-francaise-janvier-2013\/\">Vacances en Guyane Fran\u00e7aise (janvier 2013)<\/a><\/h3><div class=\"blog-post_text\"><p>Je suis de retour au Canada apr\u00e8s un voyage d&#8217; un mois en Guyane Fran\u00e7aise pour rencontrer la belle &#8211; famille.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/comment-les-baleines-font-lamour-novembre-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2012\/11\/whales-couple-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/comment-les-baleines-font-lamour-novembre-2012\/\">Comment les baleines font l&#8217;amour (novembre 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>Nous les hommes nous marchons debout. Pou commencer, nous levons les yeux vers le ciel bleu qui se d\u00e9ploie au dessus de nous, en nous tenant aussi...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2012-au-canada-octobre-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit20127-scaled-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2012-au-canada-octobre-2012\/\">Saison 2012 au Canada (octobre 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>De juin \u00e0 fin septembre 2012, j&#8217;ai pass\u00e9 348 heures (174 sorties ) en zodiac sur le fleuve Saint-Laurent. Cinq sorties de plus par rapport \u00e0...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premiere-reunion-de-lannee-de-lalliance-echo-baleine-avril-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/michael-olsen-djS1aPrSr4-unsplash-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premiere-reunion-de-lannee-de-lalliance-echo-baleine-avril-2012\/\">Premi\u00e8re r\u00e9union de l&#8217;ann\u00e9e de l&#8217;Alliance Echo-Baleine (avril 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>Hier, j&#8217; \u00e9tais invit\u00e9 \u00e0 la premi\u00e8re r\u00e9union de l'&#8221;Alliance Echo-Baleine&#8221; pr\u00e8s de mon village. Mon directeur de l&#8217;...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-a-bosse-et-rorqual-commun-en-alimentation-de-surface-autour-de-mon-bateau-juillet-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201222-1170x725.jpg' alt='Purely Magestic' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-a-bosse-et-rorqual-commun-en-alimentation-de-surface-autour-de-mon-bateau-juillet-2012\/\">Baleine \u00e0 bosse et rorqual commun en alimentation de surface autour de mon bateau (juillet 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis plus de 15 ans je suis sur l&#8217;eau \u00e0 observer les mammif\u00e8res marins. J&#8217; ai connu des sorties incroyables dans mon pass\u00e9 et celle...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/deja-des-baleines-a-bosses-megaptera-novaeangliae-et-rorquals-communs-balaenoptera-physalus-en-face-de-chez-moi-mai-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201213-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/deja-des-baleines-a-bosses-megaptera-novaeangliae-et-rorquals-communs-balaenoptera-physalus-en-face-de-chez-moi-mai-2012\/\">D\u00e9j\u00e0 des baleines \u00e0 bosses en face de chez moi ! (mai 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>Des baleines \u00e0 bosse (Megaptera novaeangliae) et rorquals communs (Balaenoptera physalus) ! Je commence ma saison sur l&#8217;eau la semaine...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/suis-je-entrain-de-changer-dethique-ou-non-avril-2012\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2012\/04\/forage-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/suis-je-entrain-de-changer-dethique-ou-non-avril-2012\/\">Suis-je entrain de changer d&#8217;\u00e9thique ou non ? (avril 2012)<\/a><\/h3><div class=\"blog-post_text\"><p>R\u00e9cemment, j&#8217;ai effectu\u00e9 une formation maritime afin de travailler l&#8217;hiver pour des compagnies priv\u00e9es. Des \u00e9quipes sont envoy\u00e9es sur...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/formation-pour-observateur-de-mammiferes-marins-et-operateur-de-systeme-dacoustique-passive-mmo\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2012\/03\/chant-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/formation-pour-observateur-de-mammiferes-marins-et-operateur-de-systeme-dacoustique-passive-mmo\/\">Formation pour &#8220;Observateur de mammif\u00e8res marins et op\u00e9rateur de syst\u00e8me d&#8217;acoustique passive (MMO) &#8220;!<\/a><\/h3><div class=\"blog-post_text\"><p>Je fais une formation de 6 jours dans mon domaine \u00e0 Grande-Rivi\u00e8re (Gasp\u00e9sie, Qu\u00e9bec &#8211; Canada) car celle-ci est Importante. Le th\u00e8me du...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/lorsquon-me-demande-de-faire-un-stage-ou-un-emploi-decembre-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2011\/12\/stage-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/lorsquon-me-demande-de-faire-un-stage-ou-un-emploi-decembre-2011\/\">Lorsqu&#8217;on me demande de faire un stage ou un emploi (d\u00e9cembre 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>Il \u00e9tait n\u00e9cessaire d\u2019apporter un \u00e9claircissement concernant ma situation professionnelle.\nDepuis que je travaille avec les mammif\u00e8res marins, je...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/un-record-7-mois-sur-leau-avec-les-baleines-en-2011-octobre-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Megaptera.Samana.Gallerie0990.mai2011-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/un-record-7-mois-sur-leau-avec-les-baleines-en-2011-octobre-2011\/\">Un record : 7 mois sur l&#8217;eau avec les baleines en 2011 ! (octobre 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis mon retour de la R\u00e9publique Dominicaine en mai 2011, je savais d\u00e9j\u00e0 que mon ann\u00e9e allait bien finir.\nJe viens de terminer ma saison...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2011-au-canada-octobre-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201113-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2011-au-canada-octobre-2011\/\">Saison 2011 au Canada (octobre 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>De juin \u00e0 d\u00e9but octobre 2011, j&#8217;ai pass\u00e9 338 heures (169 sorties ) en zodiac sur le fleuve Saint-Laurent. J&#8217;ai demand\u00e9 des photos...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2011-est-riche-en-baleine-aout-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201130-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2011-est-riche-en-baleine-aout-2011\/\">La saison 2011 est riche en baleine ! (aout 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis mon retour sur l&#8217; eau comme capitaine, je peux d\u00e9j\u00e0 raconter mes magnifiques observations avec les baleines.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/retour-sur-leau-juin-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/PhotosclientssaisonEssipit201117-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/retour-sur-leau-juin-2011\/\">Retour sur l&#8217;eau en tant que Capitaine !! (juin 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>Je suis rentr\u00e9 de la R\u00e9publique Dominicaine pour le Canada au mois de mai.\nApr\u00e8s quelques jours pass\u00e9s sur Montr\u00e9al je suis all\u00e9 directement sur...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/capitaine-ecoresponsable-pour-cet-ete\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/HumpBackwhale3.Samana.SarahCelano.janvier2011.htm-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/capitaine-ecoresponsable-pour-cet-ete\/\">Capitaine &#8220;Eco-responsable&#8221; pour cet \u00e9t\u00e9 !<\/a><\/h3><div class=\"blog-post_text\"><p>Ma saison 2011 au Canada en tant que capitaine de bateau pour observer les baleines va connaitre un nouveau d\u00e9part. En effet, les compagnies de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/santuaire-de-samana-en-republique-dominicaine-mars-2011\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2011\/03\/samana-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/santuaire-de-samana-en-republique-dominicaine-mars-2011\/\">Sanctuaire de Saman\u00e1 en R\u00e9publique Dominicaine (mars 2011)<\/a><\/h3><div class=\"blog-post_text\"><p>\u00c7a va faire une semaine que je suis arriv\u00e9 en &#8220;R\u00e9publique Dominicaine&#8221; et d\u00e9j\u00e0 6 sorties en mer.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premiere-semaine-avec-les-baleines-a-bosses-de-la-republique-dominicaine\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/samana-baleine-a-bosse-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premiere-semaine-avec-les-baleines-a-bosses-de-la-republique-dominicaine\/\">Premi\u00e8re semaine avec les baleines \u00e0 bosses de la R\u00e9publique Dominicaine<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous,\n\u00c7a va faire une semaine que je suis arriv\u00e9 en &#8220;R\u00e9publique Dominicaine&#8221; et d\u00e9j\u00e0 6 sorties en mer.\nComme promis la...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2010-au-canada-octobre-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/baleine-client15.summer2010-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2010-au-canada-octobre-2010\/\">Saison 2010 au Canada (octobre 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai termin\u00e9 la saison estivale 2010 un peu plus t\u00f4t pour rentrer en France et rejoindre la famille. Des clients m&#8217;ont envoy\u00e9s...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/quand-les-plaisanciers-nuisent-aux-baleines-aout-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/08\/bateay-propel-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/quand-les-plaisanciers-nuisent-aux-baleines-aout-2010\/\">Quand les plaisanciers nuisent aux baleines&#8230; (ao\u00fbt 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>On me demande souvent si les bateaux d\u00e9rangent les baleines et nuisent a leur comportement ?\n\u00c9videmment que le bruit des moteurs est un s\u00e9rieux...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/oh-mon-bateau-oh-oh-oh-juillet-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Julien-Marchal.Croiseres.Essipit.2010.Canada4-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/oh-mon-bateau-oh-oh-oh-juillet-2010\/\">Oh mon bateau&#8230;.Oh ! Oh ! Oh !&#8230;(juillet 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>Pour ceux qui doutaient encore de mon activit\u00e9 favorite, voici quelques photographies prisent sur le terrain&#8230;<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2010-est-partie-juin-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/06\/reserve-quebec-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2010-est-partie-juin-2010\/\">La saison 2010 est partie ! (juin 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai quitt\u00e9 Montr\u00e9al (Qu\u00e9bec, Canada) pour d\u00e9marrer la saison touristique dans le nord canadien avec les croisi\u00e8res aux baleines.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/liste-des-orques-captifs-dans-le-monde-mai-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/05\/orque-captif-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/liste-des-orques-captifs-dans-le-monde-mai-2010\/\">Liste des orques captifs dans le monde (mai 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>L&#8217;ONG &#8220;RESEAU CETACES&#8221; (France) a accept\u00e9 que je mette en ligne leur liste des orques captifs dans le monde. Tr\u00e8s int\u00e9ressant et...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/maree-noire-erika-mai-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/05\/naufrage-erika-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/maree-noire-erika-mai-2010\/\">Mar\u00e9e Noire Erika (mai 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>Je suis all\u00e9 sur la cote atlantique en 2000, exactement aux &#8220;Sables d&#8217;Olonnes&#8221;, avec la LPO (Ligue de Protection des Oiseaux),...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/excellent-article-sur-la-commission-baleiniere-internationale-2010-avril-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/04\/commission-baleiniere-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/excellent-article-sur-la-commission-baleiniere-internationale-2010-avril-2010\/\">Excellent article sur la Commission Baleini\u00e8re Internationale 2010 (avril 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour, J&#8217;invite les internautes \u00e0 lire l&#8217;excellent article sur la v\u00e9rit\u00e9 de la &#8220;CBI&#8221; (en pr\u00e9vision de la r\u00e9union) de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nouvelle-saison-estivale-2010-mars-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/baleine-client2.summer2010-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/photos-clients\/\">Photos Clients<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nouvelle-saison-estivale-2010-mars-2010\/\">Nouvelle saison estivale 2010 ! (mars 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;ai termin\u00e9 la saison estivale 2010 un peu plus t\u00f4t pour rentrer en France et rejoindre la famille. Des clients m&#8217;ont envoy\u00e9s...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/lorque-tueur-mars-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2010\/03\/tilikum-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/lorque-tueur-mars-2010\/\">L&#8217;orque tueur ? (mars 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>La mort de l\u2019entraineuse dans un parc aquatique en Floride a fait rebondir beaucoup de monde ! mais pourquoi ? \u00cates-vous surpris ?<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/un-an-et-demi-en-polynesie-fevrier-2010\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Rangiroa.FrenchPolynesia.2009-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/un-an-et-demi-en-polynesie-fevrier-2010\/\">Un an et demi en Polyn\u00e9sie (f\u00e9vrier 2010)<\/a><\/h3><div class=\"blog-post_text\"><p>Que du retard pour la mise \u00e0 jour de mon site internet depuis les deux derniers mois !. La raison est simple, la connexion sur mon \u00eele est r\u00e9duite...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/long-sos-grand-bleu-fete-ses-20-ans-decembre-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/12\/sos-grand-bleu-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/long-sos-grand-bleu-fete-ses-20-ans-decembre-2009\/\">L\u2019Ong SOS Grand Bleu f\u00eate ses 20 ans (d\u00e9cembre 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Je suis membre depuis 1997 de l\u2019association S.O.S Grand Bleu. Son bureau est situ\u00e9 dans le magnifique village de Saint-Jean-Cap-Ferrat (France),...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tous-contre-la-captivite-et-le-massacre-des-dauphins-avec-le-film-the-cove\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/10\/RickOBarry-thecove-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tous-contre-la-captivite-et-le-massacre-des-dauphins-avec-le-film-the-cove\/\">Tous contre la captivit\u00e9 et le massacre des dauphins avec le film -The Cove-<\/a><\/h3><div class=\"blog-post_text\"><p>Mr Rick O\u2019Barry est le h\u00e9ros d\u2019un documentaire, intitul\u00e9 -The Cove- (la petite baie en fran\u00e7ais), tourn\u00e9 \u00e0 Taiji au Japon, qui fait r\u00e9f\u00e9rence aux...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/depart-pour-le-canada-octobre-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/10\/polynesie-francaise-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/depart-pour-le-canada-octobre-2009\/\">D\u00e9part pour le Canada (octobre 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Du changement de mon cot\u00e9. Finalement mon employeur va vendre sa compagnie le 1er janvier 2010. Il voulait, depuis un moment le faire.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-a-bosse-photos-septembre-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Whale.Polynesia.2-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/baleine-a-bosse-photos-septembre-2009\/\">Baleine \u00e0 bosse photos (septembre 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis ma rencontre avec la baleine \u00e0 bosse le 08 ao\u00fbt 2009, beaucoup de monde souhaitait voir les photos. C&#8217;est normal.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nage-avec-une-baleine-a-bosse-megaptera-novaeangliae\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/08\/polynesie-fr-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nage-avec-une-baleine-a-bosse-megaptera-novaeangliae\/\">Nage avec une baleine \u00e0 bosse (Megaptera novaeangliae) !<\/a><\/h3><div class=\"blog-post_text\"><p>Chers visiteurs,\nIl y a des jours o\u00f9 la vie nous reserve des surprises&#8230;\nJe partais avec mon groupe de six personnes. Le capitaine, notre...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rapport-cetaces-et-raie-manta-juillet-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/07\/polynesie-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rapport-cetaces-et-raie-manta-juillet-2009\/\">Rapport, c\u00e9tac\u00e9s et raie manta (juillet 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Pas mal de retard ce mois-ci car la saison a d\u00e9marr\u00e9 rapidement. Sachant que de juillet \u00e0 d\u00e9cembre 2010, nous avons la haute saison touristique...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-pollution-visible-est-elle-la-plus-nuisible-juin-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/06\/pollution-ocean-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-pollution-visible-est-elle-la-plus-nuisible-juin-2009\/\">La pollution visible est-elle la plus nuisible (juin 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Dans mon rapport de 2002 intitul\u00e9 -La pollution et ses effets sur les c\u00e9tac\u00e9s-, en collaboration avec St\u00e9phanie Raynaud \u00e0 Montpellier (France),...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tres-bon-rapport-sur-les-orques-dans-le-detroit-de-gibraltar-in-english-avril-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/orques-gibraltar-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tres-bon-rapport-sur-les-orques-dans-le-detroit-de-gibraltar-in-english-avril-2009\/\">Tr\u00e8s bon rapport sur les orques dans le d\u00e9troit de Gibraltar (in english, avril 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>On m&#8217;a envoy\u00e9 un rapport (en anglais) dat\u00e9 de 2007, concernant les orques (Orcinus orca) qui chassent le thon dans le d\u00e9troit de Gibraltar.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/trop-tard-pour-sauver-un-requin-mars-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Requinpointenoire1-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/trop-tard-pour-sauver-un-requin-mars-2009\/\">Trop tard pour sauver un requin (mars 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Je suis en r\u00e9\u00e9ducation en ce moment pour retablir mon genou, donc je passe beaucoup de temps dans le lagon en face de mon far\u00e9 (maison...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/28-dauphins-identifies-et-interruption-du-travail-fevrier-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/02\/passe-tiputa2-1170x725.jpg' alt='Bora Bora\n\nFrench Polynesia' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/28-dauphins-identifies-et-interruption-du-travail-fevrier-2009\/\">28 dauphins identifi\u00e9s et interruption du travail (f\u00e9vrier 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>En janvier, j&#8217;avais inform\u00e9 mes lecteurs que j&#8217;avais pu identifier 19 dauphins gr\u00e2ce a la photo &#8211; identification sur la passe de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/oscar-du-meilleur-documentaire-the-cove-fevrier-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/thecove-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/oscar-du-meilleur-documentaire-the-cove-fevrier-2009\/\">Oscar du meilleur documentaire : The Cove (f\u00e9vrier 2009)<\/a><\/h3><div class=\"blog-post_text\"><p>Comme beaucoup de canadiens, nous \u00e9tions devant notre t\u00e9l\u00e9vision dimanche soir pour regarder la c\u00e9r\u00e9monie des Oscars \u00e0 Hollywood !\nLors de la...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/honte-au-troisieme-zoo-francais-pour-les-dauphins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2009\/01\/dauphins-captifs-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/honte-au-troisieme-zoo-francais-pour-les-dauphins\/\">Honte au troisi\u00e8me zoo fran\u00e7ais pour les dauphins<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;\u00e9tais un peu d\u00e9connect\u00e9 de la France ainsi que des derniers sujets concernant la captivit\u00e9 et les zoos marins.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/10-premiers-dauphins-photos-identifies-partie-1\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/TT1-B-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/10-premiers-dauphins-photos-identifies-partie-1\/\">10 premiers dauphins photos &#8211; identifi\u00e9s (partie 1)<\/a><\/h3><div class=\"blog-post_text\"><p>voici en deux parties les premi\u00e8res photos de dauphins obtenues de juillet 2008 \u00e0 janvier 2009 permettant de les identifier en mer, dans la passe...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/les-9-autres-dauphins-photos-identifies-partie-2\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/TT16-1-B-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/les-9-autres-dauphins-photos-identifies-partie-2\/\">Les 9 autres dauphins photos &#8211; identifi\u00e9s (partie 2)<\/a><\/h3><div class=\"blog-post_text\"><p>Voici la seconde partie des dauphins photographies sur Rangiroa de TT13 \u00e1 TT23<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/bonne-annee-2009\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/bonne-annee-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/bonne-annee-2009\/\">Bonne ann\u00e9e 2009<\/a><\/h3><div class=\"blog-post_text\"><p>Bonne ann\u00e9e 2009 ! Pour cette nouvelle ann\u00e9e, pas mal de chose de mon c\u00f4t\u00e9<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/19-dauphins-identifies-a-rangiroa-dec-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Bureau-de-la-Cie-Rangiroa.2008-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/19-dauphins-identifies-a-rangiroa-dec-2008\/\">19 dauphins identifi\u00e9s \u00e0 Rangiroa (dec 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>J\u2019en parlais en octobre 2008 sur mon site internet, concernant mon travail du groupe de grands dauphins (Tursiops truncatus) permanent a l\u2019ann\u00e9e...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/ma-bibliographie-sur-les-cetaces\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/book-ocean-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/ma-bibliographie-sur-les-cetaces\/\">Ma bibliographie sur les c\u00e9tac\u00e9s !<\/a><\/h3><div class=\"blog-post_text\"><p>En cette fin d&#8217;ann\u00e9e, je vous fais parvenir toute ma bibliographie des c\u00e9tac\u00e9s (en format pdf.)<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/le-canada-ne-protege-pas-ses-orques-novembre-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Rimouski.Quebec.Canada.2007-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/le-canada-ne-protege-pas-ses-orques-novembre-2008\/\">Le Canada ne prot\u00e8ge pas ses orques (novembre 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>Pas de protection pour l&#8217;habitat des \u00e9paulards : le Canada est poursuivi. Six groupes environnementaux ont lanc\u00e9 une poursuite contre P\u00eaches...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/etude-des-grands-dauphins-tursiops-truncatus-a-rangiroa\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/10\/Rangiroa-saut-grand-dauphin-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/etude-des-grands-dauphins-tursiops-truncatus-a-rangiroa\/\">\u00c9tude des grands dauphins (Tursiops truncatus) \u00e0 Rangiroa ! (oct 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>Mon travail comme guide me permet d&#8217;\u00eatre en mer tous les jours et de proposer nos deux activit\u00e9s aux clients : la descente de la passe...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premier-mois-en-polynesie-francaise-aout-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/07\/polynesie-francaise2005-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/premier-mois-en-polynesie-francaise-aout-2008\/\">Premier mois en Polyn\u00e9sie fran\u00e7aise! (ao\u00fbt 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;\u00e9tais dans l&#8217;id\u00e9e de faire ma 3\u00e8me saison estivale au Canada mais les choses ont chang\u00e9es. Je vais le faire seulement un mois...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/resume-de-la-60eme-commission-baleiniere-internationale-iwc-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/07\/baleine-filet-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/resume-de-la-60eme-commission-baleiniere-internationale-iwc-2008\/\">R\u00e9sum\u00e9 de la 60\u00e8me Commission Baleini\u00e8re Internationale (IWC) (2008)<\/a><\/h3><div class=\"blog-post_text\"><p>La Commission Baleini\u00e8re Internationale (CBI) a \u00e9t\u00e9 cr\u00e9\u00e9e par la Convention de Washington (1946) dans un contexte de surexploitation des grands...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nos-chiffres-comparatifs-de-juin-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/06\/mer-bleue-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/nos-chiffres-comparatifs-de-juin-2008\/\">Polyn\u00e9sie fran\u00e7aise &#8211; Rangiroa &#8211; Nos chiffres comparatifs de juin 2008<\/a><\/h3><div class=\"blog-post_text\"><p>Comme chaque d\u00e9but de mois, je compare nos observations dauphins de l\u2019ann\u00e9e derni\u00e8re par rapport \u00e0 la m\u00eame p\u00e9riode. Lorsque je regarde mes...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rangiroa-photos-de-mon-lieu-de-travail-septembre-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/rangiroa-aerien09-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rangiroa-photos-de-mon-lieu-de-travail-septembre-2008\/\">Rangiroa &#8211; Polyn\u00e9sie fran\u00e7aises &#8211; photos de mon lieu de travail (septembre 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>Voici des photos de la passe de Tiputa sur l&#8217;\u00eele de Rangiroa, lieu de mon travail. La passe de Tiputa relie le lagon et l&#8217;oc\u00e9an.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/bonne-saison-2008-a-tous\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Tadoussac.summer2007.Qc_.canada-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/bonne-saison-2008-a-tous\/\">Bonne saison 2008 \u00e0 tous !<\/a><\/h3><div class=\"blog-post_text\"><p>Je peux que vous souhaiter une bonne saison 2008 en mer&#8230;<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/polynesie-et-rangiroa-juin-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/06\/polynesie-francaise-rangiroa-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/polynesie-et-rangiroa-juin-2008\/\">Polyn\u00e9sie et Rangiroa (juin 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>J&#8217;\u00e9tais dans l&#8217;id\u00e9e de faire ma 3\u00e8me saison estivale au Canada mais les choses ont chang\u00e9es. Je vais le faire seulement un mois...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/troisieme-saison-estivale-au-canada-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/05\/tadoussac-canada-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/troisieme-saison-estivale-au-canada-2008\/\">Troisi\u00e8me saison estivale au Canada : 2008<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous,\nPour ma troisi\u00e8me ann\u00e9e au Qu\u00e9bec, je m\u2019en vais une fois de plus, sur les bateaux afin de travailler avec les c\u00e9tac\u00e9s.\nSeulement...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/cetaces-a-lile-maurice-mars-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/03\/ile-maurice-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/cetaces-a-lile-maurice-mars-2008\/\">C\u00e9tac\u00e9s \u00e0 l&#8217;\u00eele Maurice (Mars 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>En 1999, j&#8217;avais aid\u00e9 la scientifique Delphine Legay dans son projet de photo-identification des dauphins \u00e0 long bec (stenella longirostris)...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/dauphin-cliche-a-vendre-fev-2008\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2008\/02\/dauphins-partout-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/dauphin-cliche-a-vendre-fev-2008\/\">Dauphin, clich\u00e9 \u00e0 vendre ! (F\u00e9v 2008)<\/a><\/h3><div class=\"blog-post_text\"><p>Difficile de ne pas \u00eatre interpell\u00e9 par le nombre de photos sur les dauphins ou baleines pour les magazines. On en voit partout ! Pas vous ?<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2007-est-terminee\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Rimouski.Quebec.Canada.2007-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-saison-2007-est-terminee\/\">La Saison 2007 est termin\u00e9e<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous,\nJe suis de retour \u00e0 Montr\u00e9al (Qu\u00e9bec, Canada) depuis une semaine. Ma saison se termine avec le G.R.E.M.M (Groupe de Recherche et...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/08\/rimouski2-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2007\/\">Saison 2007<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous,\nMon message est tr\u00e8s court car j\u2019ai pas beaucoup de temps. Les baleines du fleuve Saint-Laurent (Qu\u00e9bec, Canada) sont au...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/ete-2007-avec-le-groupe-de-recherche-et-deducation-sur-les-mammiferes-marins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/07\/kayak-1170x725.jpg' alt='Kajak' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/ete-2007-avec-le-groupe-de-recherche-et-deducation-sur-les-mammiferes-marins\/\">\u00c9t\u00e9 2007 avec le Groupe de Recherche et d&#8217;\u00c9ducation sur les Mammif\u00e8res Marins<\/a><\/h3><div class=\"blog-post_text\"><p>Je pensais ne pas pouvoir travailler cet \u00e9t\u00e9 2007 sur les c\u00e9tac\u00e9s suite \u00e0 ma blessure au genou, mais j\u2019ai pu avoir une opportunit\u00e9 avec le...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/compte-rendu-de-la-59e-commission-baleiniere-internationale-iwc-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/06\/vaquita-marina-1170x725.jpeg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/compte-rendu-de-la-59e-commission-baleiniere-internationale-iwc-2007\/\">Compte-rendu de la 59e Commission Baleini\u00e8re Internationale (IWC) (2007)<\/a><\/h3><div class=\"blog-post_text\"><p>La &#8220;59 \u00e8me Commission Baleini\u00e8re Internationale \/ IWC&#8221; en Alaska vient de terminer. Ci-joint, le compte rendu de plusieurs ONG...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-surpeche-un-enjeu-majeur-juin-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/06\/surpeche-poissons-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/la-surpeche-un-enjeu-majeur-juin-2007\/\">La surp\u00eache : un enjeu majeur (juin 2007)<\/a><\/h3><div class=\"blog-post_text\"><p>Je devais donner mon opinion fasse au probl\u00e8me de la p\u00eache et de la surexploitation des oc\u00e9ans. Les oc\u00e9ans sont entrain de se vider par la...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tout-va-mal-pour-lassociation-island-expedition-avril-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/04\/teenager-dos-1170x725.jpg' alt='177737593' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/tout-va-mal-pour-lassociation-island-expedition-avril-2007\/\">Tout va mal pour l&#8217;association Island Expedition (avril 2007)<\/a><\/h3><div class=\"blog-post_text\"><p>Suite \u00e0 mon article sur l\u2019association \u00ab Island Expedition \u00bb (d\u00e9cembre 2006), j\u2019 ai re\u00e7u beaucoup d\u2019email ou de lettre \u00e0 ce sujet. Tous ces gens...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/reference-dorcalab-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/04\/orcalab-1-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/reference-dorcalab-2007\/\">R\u00e9f\u00e9rence d&#8217;Orcalab 2007<\/a><\/h3><div class=\"blog-post_text\"><p>Bonjour \u00e0 tous.\nJ&#8217;avais demand\u00e9 aux deux chercheurs d&#8217;Orcalab (Colombie-Britannique, Canada), de m&#8217;\u00e9crire un certificat...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/blessure-et-interruption-volontaire-2007\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2007\/03\/ligament-genou-1170x725.jpg' alt='The man bent her head and grabbed him at her after exercise.' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/blessure-et-interruption-volontaire-2007\/\">Blessure et interruption volontaire (2007)<\/a><\/h3><div class=\"blog-post_text\"><p>Je pratique le sport depuis de mon plus jeune age et j&#8217;ai connu quelques blessures superficielles.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/prudence-avec-lassociation-island-expedition-dec-2006\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2006\/12\/bahamas-boat-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/prudence-avec-lassociation-island-expedition-dec-2006\/\">Prudence avec l&#8217;association Island Expedition (dec 2006)<\/a><\/h3><div class=\"blog-post_text\"><p>Chers visiteurs,\nJe devais parler de mon aventure au Bahamas en 2001 avec l\u2019association Island Expedition.\nEn effet, beaucoup de monde me demande...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2006-croisieres-du-grand-heron\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/baleinebleue2006-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/saison-2006-croisieres-du-grand-heron\/\">Saison 2006 : Croisi\u00e8res du Grand H\u00e9ron<\/a><\/h3><div class=\"blog-post_text\"><p>a[data-mtli~=\"mtli_filesize4350kB\"]:after {content:\" (43.50 kB)\"}a[data-mtli~=\"mtli_filesize4400kB\"]:after {content:\" (44.00 kB)\"}Journal de Bord...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rencontre-avec-la-baleine-bleue-2006\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/0706julien21-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/rencontre-avec-la-baleine-bleue-2006\/\">Rencontre avec la baleine bleue 2006<\/a><\/h3><div class=\"blog-post_text\"><p>Photos de Johan DECELLE et Lucia DI IORIO\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nPortneuf-Sur-Mer &#8211; Qu\u00e9bec\/Canada, juillet 2006.\nJulien Marchal<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/pourquoi-fait-il-moins-froid-au-canada-juin-2006\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2000\/06\/rechauffement-ocean-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/pourquoi-fait-il-moins-froid-au-canada-juin-2006\/\">Pourquoi fait-il moins froid au Canada (juin 2006)<\/a><\/h3><div class=\"blog-post_text\"><p>Tout le monde me disait que le grand froid Canadien allait \u00eatre terrible et dure \u00e0 supporter pour mon premier hiver ! Que je regretterais...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/questions-reponses-faq-2006\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/canada-c3-1-julien-marchal-septembre-2017-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/questions-reponses-faq-2006\/\">Questions-R\u00e9ponses \/ FAQ (2006)<\/a><\/h3><div class=\"blog-post_text\"><p>Je r\u00e9ponds \u00e0 vos questions fr\u00e9quentes.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/embarquez-avec-moi-cet-ete\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2006\/04\/Portneuf-sur-Mer-canada-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/embarquez-avec-moi-cet-ete\/\">Embarquez avec moi cet \u00e9t\u00e9 ! (2006)<\/a><\/h3><div class=\"blog-post_text\"><p>En 2001, j&#8217;ai travaill\u00e9 en tant que volontaire au Qu\u00e9bec (Canada) sur les c\u00e9tac\u00e9s du fleuve Saint-Laurent \u00bb et \u00ab Swiss Cetacean Society...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/liste-alphabet-des-baleines\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/alphabet-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/liste-alphabet-des-baleines\/\">Liste Alphabet des Baleines et des Dauphins<\/a><\/h3><div class=\"blog-post_text\"><p>LISTE des mots &#8230;<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/militant-greenpeace-fevrier-2006\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/greenpeace-milit-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/militant-greenpeace-fevrier-2006\/\">Militant Greenpeace (f\u00e9vrier 2006)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis toujours, je me suis senti concern\u00e9 par les probl\u00e8mes environnementaux dans les oc\u00e9ans ou les f\u00f4rets. Mon probl\u00e8me est que je pr\u00e9f\u00e9rais...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/pourquoi-un-alphabet-des-dauphins-et-des-baleines\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2006\/01\/livres-cetaces-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/pourquoi-un-alphabet-des-dauphins-et-des-baleines\/\">Pourquoi un Alphabet des Dauphins et des Baleines ?<\/a><\/h3><div class=\"blog-post_text\"><p>Lorsque je regarde mes statistiques concernant les fichiers lu sur mon site, je constate que peu de monde regarde mes deux fichiers -Alphabet des...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/reseau-quebecois-et-francais-durgences-pour-les-mammiferes-marins\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/Rimouski.fulljob.Quebec.Canada.2007-1170x725.jpg' alt='OLYMPUS DIGITAL CAMERA' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/reseau-quebecois-et-francais-durgences-pour-les-mammiferes-marins\/\">R\u00e9seau Qu\u00e9b\u00e9cois (et Fran\u00e7ais) d&#8217;urgences pour les mammif\u00e8res marins : 1-877-722-5346<\/a><\/h3><div class=\"blog-post_text\"><p>En France, nous avons la chance d&#8217;avoir PELAGOS. Monaco, la France et l&#8217;Italie constitue chacun un groupe de travail \u00ab\u00a0sensibilisation...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/changement-dhorizon-2005\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/2can2005-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/changement-dhorizon-2005\/\">Changement d&#8217;horizon (2005)<\/a><\/h3><div class=\"blog-post_text\"><p>Depuis ma premi\u00e8re visite au Canada en 1996 avec mon sac a dos, je voulais rester plus longtemps dans ce pays. Maintenant c&#8217;est fait !...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/observation-des-cetaces-aux-acores\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2005\/07\/acores-observer-les-cetaces-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/observation-des-cetaces-aux-acores\/\">Observation des c\u00e9tac\u00e9s aux A\u00e7ores<\/a><\/h3><div class=\"blog-post_text\"><p>Programme Observation des c\u00e9tac\u00e9s aux A\u00e7ores :\n3 \u2013 9 juillet 2005\nVoyage \u00e9cotouristique : Observation des c\u00e9tac\u00e9s\nDans le sillage des dauphins et...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/entre-huitres-et-dauphins-le-bassin-darcachon-2005\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2005\/07\/arcachon-huitre-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/entre-huitres-et-dauphins-le-bassin-darcachon-2005\/\">Entre hu\u00eetres et dauphins, le bassin d&#8217;Arcachon (2005)<\/a><\/h3><div class=\"blog-post_text\"><p>Il est arriv\u00e9 dans mon enfance de venir en vacances dans la r\u00e9gion d&#8217;Aquitaine avec mes parents. Nous \u00e9tions \u00e0 Lacanau pour profiter de...<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/classification-des-cetaces-dans-le-monde\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/baleines-du-monde-thumb-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/travaux-personnels\/\">Travaux personnels<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/classification-des-cetaces-dans-le-monde\/\">Classification des c\u00e9tac\u00e9s dans le monde<\/a><\/h3><div class=\"blog-post_text\"><p>Fran\u00e7ais et Anglais<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wgl_col-6 item\"><div class=\"blog-post format-standard-image\"><div class=\"blog-post_wrapper\"><div class=\"blog-post_media\"><div class=\"blog-post_media_part\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/le-sanctuaire-pelagos-par-s-o-s-grand-bleu-mai-2004\/\" class=\"blog-post_feature-link\"><img src='https:\/\/julienmarchal.fr\/wp-content\/uploads\/2004\/05\/Grand-dauphin-Truncatus-sanctuaire-1170x725.jpg' alt='' \/><\/a><\/div><span class=\"post_meta-categories\"><span><a href=\"https:\/\/julienmarchal.fr\/en-us\/category\/blog-general\/\">Blog g\u00e9n\u00e9ral<\/a><\/span><\/span><\/div><div class=\"blog-post_content\"><div class=\"post_meta-wrap\"><\/div><h3 class=\"blog-post_title\"><a href=\"https:\/\/julienmarchal.fr\/en-us\/le-sanctuaire-pelagos-par-s-o-s-grand-bleu-mai-2004\/\">Le sanctuaire Pelagos (par S.O.S Grand Bleu, mai 2004)<\/a><\/h3><div class=\"blog-post_text\"><p>Cet espace marin prot\u00e9g\u00e9 s&#8217;\u00e9tend sur 87 500 km2, au sein du bassin Corso-Liguro-Proven\u00e7al. C&#8217;est en 1999 que la France, l&#8217;Italie...<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tout le journal Travaux personnels Photos Clients Blog g\u00e9n\u00e9ral Blog g\u00e9n\u00e9ral Cr\u00e9ation et dessins .elementor-8181 .elementor-element.elementor-element-471cb9a .elementor-heading-title{font-family:var( &#8211;e-global-typography-secondary-font-family&#8230; Blog g\u00e9n\u00e9ral Guide des mammif\u00e8res marins de l\u2019\u00eele Maurice de Delphine Legay (1999) J\u2019ai connu Delphine Legay en 1999 pour avoir travaill\u00e9 avec elle sur l\u2019\u00cele Maurice et Iles Rodrigues. Ce guide est un bel hommage. Photos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6526","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JULIEN MARCHAL &#8212; Journal de Bord<\/title>\n<meta name=\"description\" content=\"Journal de bord, travaux personnels, photographies des clients, blog, dessins, saison des baleines ou dauphins par Julien Marchal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/julienmarchal.fr\/en-us\/logbook\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JULIEN MARCHAL &#8212; Journal de Bord\" \/>\n<meta property=\"og:description\" content=\"Journal de bord, travaux personnels, photographies des clients, blog, dessins, saison des baleines ou dauphins par Julien Marchal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/julienmarchal.fr\/en-us\/logbook\/\" \/>\n<meta property=\"og:site_name\" content=\"JULIEN MARCHAL\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-09T22:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/\",\"name\":\"JULIEN MARCHAL &#8212; Journal de Bord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GalerieDessins2023.1.JM_-1170x725.jpeg\",\"datePublished\":\"2023-02-02T02:21:05+00:00\",\"dateModified\":\"2023-03-09T22:20:18+00:00\",\"description\":\"Journal de bord, travaux personnels, photographies des clients, blog, dessins, saison des baleines ou dauphins par Julien Marchal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GalerieDessins2023.1.JM_-1170x725.jpeg\",\"contentUrl\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/GalerieDessins2023.1.JM_-1170x725.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/journal-de-bord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/julienmarchal.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journal de Bord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#website\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/\",\"name\":\"JULIEN MARCHAL, Observateur de mammif\u00e8res marins\",\"description\":\"Observateur Mammif\u00e8res marins\",\"publisher\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#\\\/schema\\\/person\\\/9bad5d6d81f92720eaf6c4750c93b7c5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/julienmarchal.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#\\\/schema\\\/person\\\/9bad5d6d81f92720eaf6c4750c93b7c5\",\"name\":\"Julien Marchal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"contentUrl\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"width\":1239,\"height\":711,\"caption\":\"Julien Marchal\"},\"logo\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/julienligniermarchal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/julien-lignier-marchal\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JULIEN MARCHAL - Logbook","description":"Diary, personal work, photographs of clients, blog, drawings, whale or dolphin season by Julien Marchal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/julienmarchal.fr\/en-us\/logbook\/","og_locale":"en_US","og_type":"article","og_title":"JULIEN MARCHAL &#8212; Journal de Bord","og_description":"Journal de bord, travaux personnels, photographies des clients, blog, dessins, saison des baleines ou dauphins par Julien Marchal","og_url":"https:\/\/julienmarchal.fr\/en-us\/logbook\/","og_site_name":"JULIEN MARCHAL","article_modified_time":"2023-03-09T22:20:18+00:00","og_image":[{"url":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/","url":"https:\/\/julienmarchal.fr\/journal-de-bord\/","name":"JULIEN MARCHAL - Logbook","isPartOf":{"@id":"https:\/\/julienmarchal.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/#primaryimage"},"image":{"@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/#primaryimage"},"thumbnailUrl":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg","datePublished":"2023-02-02T02:21:05+00:00","dateModified":"2023-03-09T22:20:18+00:00","description":"Diary, personal work, photographs of clients, blog, drawings, whale or dolphin season by Julien Marchal","breadcrumb":{"@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/julienmarchal.fr\/journal-de-bord\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/#primaryimage","url":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg","contentUrl":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/GalerieDessins2023.1.JM_-1170x725.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/julienmarchal.fr\/journal-de-bord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/julienmarchal.fr\/"},{"@type":"ListItem","position":2,"name":"Journal de Bord"}]},{"@type":"WebSite","@id":"https:\/\/julienmarchal.fr\/#website","url":"https:\/\/julienmarchal.fr\/","name":"JULIEN MARCHAL, Marine mammal observer","description":"Marine Mammal Observer","publisher":{"@id":"https:\/\/julienmarchal.fr\/#\/schema\/person\/9bad5d6d81f92720eaf6c4750c93b7c5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/julienmarchal.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/julienmarchal.fr\/#\/schema\/person\/9bad5d6d81f92720eaf6c4750c93b7c5","name":"Julien Marchal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","url":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","contentUrl":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","width":1239,"height":711,"caption":"Julien Marchal"},"logo":{"@id":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png"},"sameAs":["https:\/\/www.instagram.com\/julienligniermarchal\/","https:\/\/www.linkedin.com\/in\/julien-lignier-marchal\/"]}]}},"_links":{"self":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages\/6526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/comments?post=6526"}],"version-history":[{"count":0,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages\/6526\/revisions"}],"wp:attachment":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/media?parent=6526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}