{"id":4839,"date":"2023-01-19T23:03:36","date_gmt":"2023-01-19T22:03:36","guid":{"rendered":"https:\/\/julienmarchal.fr\/?page_id=4839"},"modified":"2023-03-09T23:29:33","modified_gmt":"2023-03-09T22:29:33","slug":"thanks","status":"publish","type":"page","link":"https:\/\/julienmarchal.fr\/en-us\/remerciements\/","title":{"rendered":"Acknowledgements"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4839\" class=\"elementor elementor-4839\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bb63d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bb63d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da3f58b\" data-id=\"da3f58b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a735c6 elementor-widget elementor-widget-heading\" data-id=\"8a735c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I would like to thank<br>\nthose who have contributed in any way to my success:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391f2a4 elementor-widget elementor-widget-heading\" data-id=\"391f2a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">France<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d5c4c8 elementor-widget elementor-widget-text-editor\" data-id=\"8d5c4c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>My parents in Alsace, without them I would never have been able to contribute to my work and my travels. Thank you for trusting me! Without you, I am nothing! I love you !<\/p><p>* Sandra Marchal, my wife Christine Parris (who has been with me for 20 years) and our little mermaid: Sa\u00efna Parris Marchal, Pascal Correggio in Manosque and Sergio Cuerda in London, my cousin Phillippe\/Philou Marchal and his family in Alsace, all my childhood friends: Gregoire Margotin , Benjamin Louis (since the age of 4 !), Damien Cixous, Boris Uebel, his wife B\u00e9n\u00e9dicte Kirchner (and my cousin!) and their daughter, Laetitia Hiriart, Claude Haffner (and his daughter), Christian Kiefer, Christophe Ptak, Jean le \"Coiffeur\" (he has all my postcards since he was a child), Franck Schrafstetter who proposed to launch my web site more than 25 years ago, Karim Nariat (Montpellier) and Steve Elliot for the help in translation<\/p><p>* All those met at the Convent of Morsiglia (Corsica, Cap Corse).<\/p><p>* All those who helped me with my book: Natacha Bernal, Andr\u00e9 Martinez, Jean-Pierre Sidois (former director of S.O.S. Grand Bleu) who published all my articles and was able to collaborate with me for many years, Ali (A la mer A la mer) and his family from Grande-Motte, Genevi\u00e8ve and Jean-Philippe Legay, St\u00e9phanie Raynaud, Christophe Guinet, Ali Soltanshahi from Esplanade, and Claude Amiel from the school of S\u00e8te and the university of Montpellier II.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87efb06 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"87efb06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9536af2 elementor-widget elementor-widget-heading\" data-id=\"9536af2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Brazil<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d749310 elementor-widget elementor-widget-text-editor\" data-id=\"d749310\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Daniela Decastro and her family.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaec60b elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"eaec60b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c30378 elementor-widget elementor-widget-heading\" data-id=\"0c30378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Guadeloupe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5113ca8 elementor-widget elementor-widget-heading\" data-id=\"5113ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">(French West Indies)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2fe055 elementor-widget elementor-widget-text-editor\" data-id=\"a2fe055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Isabelle Chaperon and Jean-Marie Cuvillier who is no longer of this world.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c211b elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c5c211b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-987775a elementor-widget elementor-widget-heading\" data-id=\"987775a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pelagos Sanctuary<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8e2003 elementor-widget elementor-widget-heading\" data-id=\"c8e2003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">(Mediterranean)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf60b2 elementor-widget elementor-widget-text-editor\" data-id=\"dbf60b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sigi Lueber (A.S.M.S, Switzerland).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50da7c4 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"50da7c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e85e43 elementor-widget elementor-widget-heading\" data-id=\"9e85e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Switzerland<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61d3b2f elementor-widget elementor-widget-text-editor\" data-id=\"61d3b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Max-Olivier Bourcoud (Swiss Cetacean Society), G\u00e9rard and his schooner Chundra Lela and Gilles Martin and his boat Coeruleoalba.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5dacfd elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b5dacfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d272317 elementor-widget elementor-widget-heading\" data-id=\"d272317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Belgium<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b00042e elementor-widget elementor-widget-text-editor\" data-id=\"b00042e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Yvon Godefroid (NGO, Dauphins libres et dauphins captifs), unfortunately deceased, who had published my report on the Parc Asterix and fought against captivity and Jean Mois (La Baleine Libre).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb727bd elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fb727bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600d283 elementor-widget elementor-widget-heading\" data-id=\"600d283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mauritius and Rodrigues<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb79ebc elementor-widget elementor-widget-text-editor\" data-id=\"eb79ebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mrs. Manilkhan and Delphine Legay (ex-director of Ceta Squale), a great thought for this scientist whose work on cetaceans I helped, unfortunately disappeared too early in the middle of the dolphins.\u00a0<\/p><p>* For those who helped me with my book: Genevi\u00e8ve and Jean-Philippe Legay.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c299e88 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c299e88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e6d9f elementor-widget elementor-widget-heading\" data-id=\"17e6d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Azores<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20452b elementor-widget elementor-widget-heading\" data-id=\"f20452b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">(Portugal)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a410a78 elementor-widget elementor-widget-text-editor\" data-id=\"a410a78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Flavia Azevedo and her family, who had the patience and kindness to transmit to me the tradition, the culture and the love of the island of Pico, the Town Hall of Lajes do Pico, the director and the staff of the museum for their documentation and explanation and Rithinia, former whaler, telling me about his exploits with a \"gin-tonic\" and a typical dish prepared with love by his wife.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9edb106 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9edb106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69067d3 elementor-widget elementor-widget-heading\" data-id=\"69067d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bahamas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce34ad8 elementor-widget elementor-widget-text-editor\" data-id=\"ce34ad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alexandre Videcoq.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-616f200 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"616f200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-861b541 elementor-widget elementor-widget-heading\" data-id=\"861b541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Canada<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab89cc elementor-widget elementor-widget-heading\" data-id=\"0ab89cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">(East and West)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0113e8 elementor-widget elementor-widget-text-editor\" data-id=\"a0113e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Robert Michaud and all his team from G.R.E.M. (Tadoussac) in 2000, Paul Spong and all the team from ORCALAB (BC) in 1997, R\u00e9gina Flores, Jeannot B\u00e9langer (sadly deceased) and his dog Kim, Monique B\u00e9langer, Dominique Emond, Colette Morin (deceased in 2022) on Bergeronnes, Hugues Desrochers (Chief Captain and trainer at Essipit), Suzie Gagnon, Mathilde Par\u00e9-D\u00e9silets and Brian Cox.<\/p><p>* For those who helped me with my book: Elise Mass\u00e9 and Christine Gilliet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a320014 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a320014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2685ebb elementor-widget elementor-widget-heading\" data-id=\"2685ebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">French Polynesia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41ea1eb elementor-widget elementor-widget-text-editor\" data-id=\"41ea1eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The families in Teapata, Tamati (with Sonia) and Hugo on Rangiroa, Oliver Martin from Bora-Bora and Moana from Rangiroa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdcdd17 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fdcdd17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e26214 elementor-widget elementor-widget-text-editor\" data-id=\"9e26214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A small tribute to Mr Rich (former Photorep store in Strasbourg) for having launched me in photography, rest in peace.<\/p><p>* <span lang=\"FR\">In memory of : Benoit Mariau, Yvon Godefroid, Delphine Legay, Jeannot B\u00e9langer and Kim, Jean-Marie Cuvillier, Mme Manilkhan, Colette Morin and Jean-Paul Marchal.<\/span><\/p><p>* <span lang=\"FR\">To those I haven't heard from yet: Yusuf Ibrahim and Laurent Wolff.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1f9742 elementor-widget elementor-widget-text-editor\" data-id=\"f1f9742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Without forgetting, all the mammals and marine animals met since 25 years...<br \/>...you motivate my life!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Je voudrais remercier ceux qui ont contribu\u00e9 de pr\u00e8s ou de loin \u00e0 ma r\u00e9ussite : France Mes parents en Alsace, sans eux jamais j&#8217; aurais pu contribuer \u00e0 mon travail et mes voyages. Merci \u00e0 vous de m&#8217; avoir fait confiance ! sans vous, je ne suis rien ! I love you ! * [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4839","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JULIEN MARCHAL &#8212; Remerciements<\/title>\n<meta name=\"description\" content=\"Remerciements pour ma famille, amis ou amies, hommages personnels et coll\u00e8gues de travail par Julien Marchal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/julienmarchal.fr\/en-us\/thanks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JULIEN MARCHAL &#8212; Remerciements\" \/>\n<meta property=\"og:description\" content=\"Remerciements pour ma famille, amis ou amies, hommages personnels et coll\u00e8gues de travail par Julien Marchal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/julienmarchal.fr\/en-us\/thanks\/\" \/>\n<meta property=\"og:site_name\" content=\"JULIEN MARCHAL\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-09T22:29:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/hanson-lu-HGWqqacbcyc-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/remerciements\\\/\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/remerciements\\\/\",\"name\":\"JULIEN MARCHAL &#8212; Remerciements\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#website\"},\"datePublished\":\"2023-01-19T22:03:36+00:00\",\"dateModified\":\"2023-03-09T22:29:33+00:00\",\"description\":\"Remerciements pour ma famille, amis ou amies, hommages personnels et coll\u00e8gues de travail par Julien Marchal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/remerciements\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/julienmarchal.fr\\\/remerciements\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/remerciements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/julienmarchal.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remerciements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#website\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/\",\"name\":\"JULIEN MARCHAL, Observateur de mammif\u00e8res marins\",\"description\":\"Observateur Mammif\u00e8res marins\",\"publisher\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#\\\/schema\\\/person\\\/9bad5d6d81f92720eaf6c4750c93b7c5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/julienmarchal.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/#\\\/schema\\\/person\\\/9bad5d6d81f92720eaf6c4750c93b7c5\",\"name\":\"Julien Marchal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"url\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"contentUrl\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\",\"width\":1239,\"height\":711,\"caption\":\"Julien Marchal\"},\"logo\":{\"@id\":\"https:\\\/\\\/julienmarchal.fr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/julien-marchal-debuts.png\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/julienligniermarchal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/julien-lignier-marchal\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JULIEN MARCHAL - Acknowledgements","description":"Thanks for my family, friends, personal tributes and work colleagues by Julien Marchal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/julienmarchal.fr\/en-us\/thanks\/","og_locale":"en_US","og_type":"article","og_title":"JULIEN MARCHAL &#8212; Remerciements","og_description":"Remerciements pour ma famille, amis ou amies, hommages personnels et coll\u00e8gues de travail par Julien Marchal","og_url":"https:\/\/julienmarchal.fr\/en-us\/thanks\/","og_site_name":"JULIEN MARCHAL","article_modified_time":"2023-03-09T22:29:33+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/01\/hanson-lu-HGWqqacbcyc-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/julienmarchal.fr\/remerciements\/","url":"https:\/\/julienmarchal.fr\/remerciements\/","name":"JULIEN MARCHAL - Acknowledgements","isPartOf":{"@id":"https:\/\/julienmarchal.fr\/#website"},"datePublished":"2023-01-19T22:03:36+00:00","dateModified":"2023-03-09T22:29:33+00:00","description":"Thanks for my family, friends, personal tributes and work colleagues by Julien Marchal","breadcrumb":{"@id":"https:\/\/julienmarchal.fr\/remerciements\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/julienmarchal.fr\/remerciements\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/julienmarchal.fr\/remerciements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/julienmarchal.fr\/"},{"@type":"ListItem","position":2,"name":"Remerciements"}]},{"@type":"WebSite","@id":"https:\/\/julienmarchal.fr\/#website","url":"https:\/\/julienmarchal.fr\/","name":"JULIEN MARCHAL, Marine mammal observer","description":"Marine Mammal Observer","publisher":{"@id":"https:\/\/julienmarchal.fr\/#\/schema\/person\/9bad5d6d81f92720eaf6c4750c93b7c5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/julienmarchal.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/julienmarchal.fr\/#\/schema\/person\/9bad5d6d81f92720eaf6c4750c93b7c5","name":"Julien Marchal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","url":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","contentUrl":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png","width":1239,"height":711,"caption":"Julien Marchal"},"logo":{"@id":"https:\/\/julienmarchal.fr\/wp-content\/uploads\/2023\/02\/julien-marchal-debuts.png"},"sameAs":["https:\/\/www.instagram.com\/julienligniermarchal\/","https:\/\/www.linkedin.com\/in\/julien-lignier-marchal\/"]}]}},"_links":{"self":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages\/4839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/comments?post=4839"}],"version-history":[{"count":0,"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/pages\/4839\/revisions"}],"wp:attachment":[{"href":"https:\/\/julienmarchal.fr\/en-us\/wp-json\/wp\/v2\/media?parent=4839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}